{"id":550,"count":5,"description":"","link":"https:\/\/interdesign.com.pt\/pt\/marca\/white\/","name":"White","slug":"white","taxonomy":"product_brand","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>White - Interdesign<\/title>\n<meta name=\"description\" content=\"Explore the latest design pieces from the White collection. At Interdesign, our specialists are here to guide you.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"White - Interdesign\" \/>\n<meta property=\"og:description\" content=\"Explore the latest design pieces from the White collection. At Interdesign, our specialists are here to guide you.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interdesign.com.pt\/pt\/marca\/white\/\" \/>\n<meta property=\"og:site_name\" content=\"Interdesign\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/interdesign.com.pt\\\/en\\\/brand\\\/white\\\/\",\"url\":\"https:\\\/\\\/interdesign.com.pt\\\/en\\\/brand\\\/white\\\/\",\"name\":\"White - Interdesign\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interdesign.com.pt\\\/pt\\\/#website\"},\"description\":\"Explore the latest design pieces from the White collection. At Interdesign, our specialists are here to guide you.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interdesign.com.pt\\\/en\\\/brand\\\/white\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interdesign.com.pt\\\/en\\\/brand\\\/white\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interdesign.com.pt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"White\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interdesign.com.pt\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/interdesign.com.pt\\\/pt\\\/\",\"name\":\"Interdesign\",\"description\":\"Mobili\u00e1rio, Interiores &amp; Decora\u00e7\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/interdesign.com.pt\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interdesign.com.pt\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interdesign.com.pt\\\/pt\\\/#organization\",\"name\":\"Interdesign\",\"url\":\"https:\\\/\\\/interdesign.com.pt\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/interdesign.com.pt\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interdesign.com.pt\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/interdesign-logo.svg\",\"contentUrl\":\"https:\\\/\\\/interdesign.com.pt\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/interdesign-logo.svg\",\"caption\":\"Interdesign\"},\"image\":{\"@id\":\"https:\\\/\\\/interdesign.com.pt\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"White - Interdesign","description":"Explore the latest design pieces from the White collection. At Interdesign, our specialists are here to guide you.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_PT","og_type":"article","og_title":"White - Interdesign","og_description":"Explore the latest design pieces from the White collection. At Interdesign, our specialists are here to guide you.","og_url":"https:\/\/interdesign.com.pt\/pt\/marca\/white\/","og_site_name":"Interdesign","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/interdesign.com.pt\/en\/brand\/white\/","url":"https:\/\/interdesign.com.pt\/en\/brand\/white\/","name":"White - Interdesign","isPartOf":{"@id":"https:\/\/interdesign.com.pt\/pt\/#website"},"description":"Explore the latest design pieces from the White collection. At Interdesign, our specialists are here to guide you.","breadcrumb":{"@id":"https:\/\/interdesign.com.pt\/en\/brand\/white\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/interdesign.com.pt\/en\/brand\/white\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interdesign.com.pt\/en\/"},{"@type":"ListItem","position":2,"name":"White"}]},{"@type":"WebSite","@id":"https:\/\/interdesign.com.pt\/pt\/#website","url":"https:\/\/interdesign.com.pt\/pt\/","name":"Interdesign","description":"Mobili\u00e1rio, Interiores &amp; Decora\u00e7\u00e3o","publisher":{"@id":"https:\/\/interdesign.com.pt\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interdesign.com.pt\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/interdesign.com.pt\/pt\/#organization","name":"Interdesign","url":"https:\/\/interdesign.com.pt\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/interdesign.com.pt\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/interdesign.com.pt\/wp-content\/uploads\/2025\/03\/interdesign-logo.svg","contentUrl":"https:\/\/interdesign.com.pt\/wp-content\/uploads\/2025\/03\/interdesign-logo.svg","caption":"Interdesign"},"image":{"@id":"https:\/\/interdesign.com.pt\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/interdesign.com.pt\/pt\/wp-json\/wp\/v2\/product_brand\/550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interdesign.com.pt\/pt\/wp-json\/wp\/v2\/product_brand"}],"about":[{"href":"https:\/\/interdesign.com.pt\/pt\/wp-json\/wp\/v2\/taxonomies\/product_brand"}],"wp:post_type":[{"href":"https:\/\/interdesign.com.pt\/pt\/wp-json\/wp\/v2\/product?product_brand=550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}